{"id":676,"date":"2015-02-25T13:45:31","date_gmt":"2015-02-25T13:45:31","guid":{"rendered":"http:\/\/locallivingwp.itravelsoftware.com\/?page_id=676"},"modified":"2015-02-25T14:16:03","modified_gmt":"2015-02-25T14:16:03","slug":"travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living","status":"publish","type":"page","link":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/","title":{"rendered":"Travel to Tuscany, Italy &#8211; Vacation, holiday and travel packages &#8211; Local Living"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-category-search-results.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-676","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Travel to Tuscany, Italy - Vacation, holiday and travel packages - Local Living - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel to Tuscany, Italy - Vacation, holiday and travel packages - Local Living\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-25T14:16:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/en\\\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/en\\\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\\\/\",\"name\":\"Travel to Tuscany, Italy - Vacation, holiday and travel packages - Local Living - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2015-02-25T13:45:31+00:00\",\"dateModified\":\"2015-02-25T14:16:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/en\\\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/en\\\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/en\\\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel to Tuscany, Italy &#8211; Vacation, holiday and travel packages &#8211; Local Living\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Travel to Tuscany, Italy - Vacation, holiday and travel packages - Local Living - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/","og_locale":"en_US","og_type":"article","og_title":"Travel to Tuscany, Italy - Vacation, holiday and travel packages - Local Living","og_url":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","article_modified_time":"2015-02-25T14:16:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/","url":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/","name":"Travel to Tuscany, Italy - Vacation, holiday and travel packages - Local Living - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2015-02-25T13:45:31+00:00","dateModified":"2015-02-25T14:16:03+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/en\/travel-to-tuscany-italy-vacation-holiday-and-travel-packages-local-living\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Travel to Tuscany, Italy &#8211; Vacation, holiday and travel packages &#8211; Local Living"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages\/676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=676"}],"version-history":[{"count":1,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages\/676\/revisions"}],"predecessor-version":[{"id":677,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages\/676\/revisions\/677"}],"wp:attachment":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media?parent=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}