{"id":8854,"date":"2026-01-09T09:17:12","date_gmt":"2026-01-09T09:17:12","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519.jpg"},"modified":"2026-01-09T09:17:12","modified_gmt":"2026-01-09T09:17:12","slug":"flowers-9115519-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/terms-of-business\/flowers-9115519-2\/","title":{"rendered":"flowers-9115519"},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-8854","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>flowers-9115519 - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"flowers-9115519 - Localliving\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/flowers-9115519-scaled.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/flowers-9115519-scaled.jpg\",\"name\":\"flowers-9115519 - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2026-01-09T09:17:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/flowers-9115519-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/flowers-9115519-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/flowers-9115519-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of Business\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/terms-of-business\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"flowers-9115519\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"flowers-9115519 - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"flowers-9115519 - Localliving","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","og_image":[{"width":2560,"height":1616,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg","name":"flowers-9115519 - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2026-01-09T09:17:12+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Terms of Business","item":"https:\/\/localliving.dk\/en\/terms-of-business\/"},{"@type":"ListItem","position":3,"name":"flowers-9115519"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"189\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-300x189.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-300x189.jpg 300w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-1024x646.jpg 1024w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-768x485.jpg 768w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-1536x970.jpg 1536w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-2048x1293.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1616,"file":"2026\/01\/flowers-9115519-scaled.jpg","filesize":413052,"sizes":{"medium":{"file":"flowers-9115519-300x189.jpg","width":300,"height":189,"filesize":13419,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-300x189.jpg"},"large":{"file":"flowers-9115519-1024x646.jpg","width":1024,"height":646,"filesize":100034,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-1024x646.jpg"},"thumbnail":{"file":"flowers-9115519-150x150.jpg","width":150,"height":150,"filesize":6459,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-150x150.jpg"},"medium_large":{"file":"flowers-9115519-768x485.jpg","width":768,"height":485,"filesize":64323,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-768x485.jpg"},"1536x1536":{"file":"flowers-9115519-1536x970.jpg","width":1536,"height":970,"filesize":185789,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-1536x970.jpg"},"2048x2048":{"file":"flowers-9115519-2048x1293.jpg","width":2048,"height":1293,"filesize":290783,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-2048x1293.jpg"},"homepage-banner-lg":{"file":"flowers-9115519-1980x800.jpg","width":1980,"height":800,"filesize":195547,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-1980x800.jpg"},"homepage-banner-md":{"file":"flowers-9115519-1170x800.jpg","width":1170,"height":800,"filesize":131703,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-1170x800.jpg"},"homepage-banner-sm":{"file":"flowers-9115519-970x440.jpg","width":970,"height":440,"filesize":73803,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-970x440.jpg"},"homepage-banner-xs":{"file":"flowers-9115519-750x440.jpg","width":750,"height":440,"filesize":59477,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-750x440.jpg"},"homepage-coupled-image":{"file":"flowers-9115519-4586x224.jpg","width":4586,"height":224,"filesize":85364,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-4586x224.jpg"},"homepage-coupled-image-xs":{"file":"flowers-9115519-750x224.jpg","width":750,"height":224,"filesize":30642,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-750x224.jpg"},"homepage-omrader":{"file":"flowers-9115519-970x440.jpg","width":970,"height":440,"filesize":73803,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-970x440.jpg"},"homepage-underbanner-first":{"file":"flowers-9115519-223x332.jpg","width":223,"height":332,"filesize":17539,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-223x332.jpg"},"homepage-underbanner-last":{"file":"flowers-9115519-234x332.jpg","width":234,"height":332,"filesize":18696,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-234x332.jpg"},"homepage-underbanner-middle":{"file":"flowers-9115519-239x162.jpg","width":239,"height":162,"filesize":9732,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-239x162.jpg"},"city-image":{"file":"flowers-9115519-239x162.jpg","width":239,"height":162,"filesize":9732,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-239x162.jpg"},"static-page-featured-image":{"file":"flowers-9115519-840x310.jpg","width":840,"height":310,"filesize":47502,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-840x310.jpg"},"category-results-stripe":{"file":"flowers-9115519-4586x245.jpg","width":4586,"height":245,"filesize":94468,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-4586x245.jpg"},"full":{"file":"flowers-9115519-scaled.jpg","width":2560,"height":1616,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"flowers-9115519.jpg"},"post":2288,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/flowers-9115519-scaled.jpg","filename":"flowers-9115519.jpg","filesize":413052,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/8854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=8854"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2288,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages\/2288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}