{"id":8836,"date":"2026-01-08T14:21:26","date_gmt":"2026-01-08T14:21:26","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto.jpg"},"modified":"2026-01-08T14:21:57","modified_gmt":"2026-01-08T14:21:57","slug":"fiera-mercato-all-aperto-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/markets-in-tuscany\/fiera-mercato-all-aperto-2\/","title":{"rendered":"fiera, mercato all aperto"},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-8836","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>fiera, mercato all aperto - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fiera, mercato all aperto - Localliving\" \/>\n<meta property=\"og:description\" content=\"Pbstmarkt, p\u00e8iazza delle erbe, portici, lauben, santo gabriele, forst, franziskaner, moir\u00e8, eccetera, mille e un vino, am\u00f2, piazza della vittoria, pizza, gelato, colazione, pane, panificio, beckerei, eisdiele, aperitivo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T14:21:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiera-mercato-all-aperto-scaled.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiera-mercato-all-aperto-scaled.jpg\",\"name\":\"fiera, mercato all aperto - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2026-01-08T14:21:26+00:00\",\"dateModified\":\"2026-01-08T14:21:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiera-mercato-all-aperto-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiera-mercato-all-aperto-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiera-mercato-all-aperto-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Markets in Tuscany\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/markets-in-tuscany\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"fiera, mercato all aperto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"fiera, mercato all aperto - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"fiera, mercato all aperto - Localliving","og_description":"Pbstmarkt, p\u00e8iazza delle erbe, portici, lauben, santo gabriele, forst, franziskaner, moir\u00e8, eccetera, mille e un vino, am\u00f2, piazza della vittoria, pizza, gelato, colazione, pane, panificio, beckerei, eisdiele, aperitivo","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","article_modified_time":"2026-01-08T14:21:57+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg","name":"fiera, mercato all aperto - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2026-01-08T14:21:26+00:00","dateModified":"2026-01-08T14:21:57+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Markets in Tuscany","item":"https:\/\/localliving.dk\/en\/markets-in-tuscany\/"},{"@type":"ListItem","position":3,"name":"fiera, mercato all aperto"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled-e1767882147734.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Fiera,\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-300x200.jpg 300w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-1024x683.jpg 1024w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-768x512.jpg 768w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-1536x1024.jpg 1536w, https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Fiera, \u00e5bent lokalt marked italien<\/p>\n"},"caption":{"rendered":"<p>Pbstmarkt, p\u00e8iazza delle erbe, portici, lauben, santo gabriele, forst, franziskaner, moir\u00e8, eccetera, mille e un vino, am\u00f2, piazza della vittoria, pizza, gelato, colazione, pane, panificio, beckerei, eisdiele, aperitivo<\/p>\n"},"alt_text":"Fiera, ","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2026\/01\/fiera-mercato-all-aperto-scaled.jpg","filesize":932702,"sizes":{"medium":{"file":"fiera-mercato-all-aperto-300x200.jpg","width":300,"height":200,"filesize":39883,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-300x200.jpg"},"large":{"file":"fiera-mercato-all-aperto-1024x683.jpg","width":1024,"height":683,"filesize":218978,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-1024x683.jpg"},"thumbnail":{"file":"fiera-mercato-all-aperto-150x150.jpg","width":150,"height":150,"filesize":25556,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-150x150.jpg"},"medium_large":{"file":"fiera-mercato-all-aperto-768x512.jpg","width":768,"height":512,"filesize":139714,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-768x512.jpg"},"1536x1536":{"file":"fiera-mercato-all-aperto-1536x1024.jpg","width":1536,"height":1024,"filesize":416588,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-1536x1024.jpg"},"2048x2048":{"file":"fiera-mercato-all-aperto-2048x1365.jpg","width":2048,"height":1365,"filesize":660149,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-2048x1365.jpg"},"homepage-banner-lg":{"file":"fiera-mercato-all-aperto-1980x800.jpg","width":1980,"height":800,"filesize":432934,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-1980x800.jpg"},"homepage-banner-md":{"file":"fiera-mercato-all-aperto-1170x800.jpg","width":1170,"height":800,"filesize":274922,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-1170x800.jpg"},"homepage-banner-sm":{"file":"fiera-mercato-all-aperto-970x440.jpg","width":970,"height":440,"filesize":155737,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-970x440.jpg"},"homepage-banner-xs":{"file":"fiera-mercato-all-aperto-750x440.jpg","width":750,"height":440,"filesize":124884,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-750x440.jpg"},"homepage-coupled-image":{"file":"fiera-mercato-all-aperto-3000x224.jpg","width":3000,"height":224,"filesize":113964,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-3000x224.jpg"},"homepage-coupled-image-xs":{"file":"fiera-mercato-all-aperto-750x224.jpg","width":750,"height":224,"filesize":77946,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-750x224.jpg"},"homepage-omrader":{"file":"fiera-mercato-all-aperto-970x440.jpg","width":970,"height":440,"filesize":155737,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-970x440.jpg"},"homepage-underbanner-first":{"file":"fiera-mercato-all-aperto-223x332.jpg","width":223,"height":332,"filesize":41738,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-223x332.jpg"},"homepage-underbanner-last":{"file":"fiera-mercato-all-aperto-234x332.jpg","width":234,"height":332,"filesize":43344,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-234x332.jpg"},"homepage-underbanner-middle":{"file":"fiera-mercato-all-aperto-239x162.jpg","width":239,"height":162,"filesize":32338,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-239x162.jpg"},"city-image":{"file":"fiera-mercato-all-aperto-239x162.jpg","width":239,"height":162,"filesize":32338,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-239x162.jpg"},"static-page-featured-image":{"file":"fiera-mercato-all-aperto-840x310.jpg","width":840,"height":310,"filesize":108845,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-840x310.jpg"},"category-results-stripe":{"file":"fiera-mercato-all-aperto-3000x245.jpg","width":3000,"height":245,"filesize":160171,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-3000x245.jpg"},"full":{"file":"fiera-mercato-all-aperto-scaled-e1767882147734.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled-e1767882147734.jpg"}},"image_meta":{"aperture":"4.5","credit":"LUCA GUADAGNINI \/ LINEEMATICHE","camera":"Canon EOS 5D Mark IV","caption":"Pbstmarkt, p\u00e8iazza delle erbe, portici, lauben, santo gabriele, forst, franziskaner, moir\u00e8, eccetera, mille e un vino, am\u00f2, piazza della vittoria, pizza, gelato, colazione, pane, panificio, beckerei, eisdiele, aperitivo","created_timestamp":"1618485286","copyright":"LUCA GUADAGNINI \/ LINEEMATICHE","focal_length":"75","iso":"100","shutter_speed":"0.004","title":"","orientation":"1","keywords":[]},"original_image":"fiera-mercato-all-aperto.jpg"},"post":8772,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2026\/01\/fiera-mercato-all-aperto-scaled-e1767882147734.jpg","filename":"fiera-mercato-all-aperto.jpg","filesize":932702,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/8836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=8836"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":8772,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages\/8772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}