{"id":7876,"date":"2024-10-18T09:59:53","date_gmt":"2024-10-18T09:59:53","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916.jpg"},"modified":"2024-10-18T09:59:53","modified_gmt":"2024-10-18T09:59:53","slug":"wine-2853916-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/wine-2853916-2\/","title":{"rendered":"wine-2853916"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-7876","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>wine-2853916 - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"wine-2853916 - Localliving\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wine-2853916-scaled-e1729245625815.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wine-2853916-scaled-e1729245625815.jpg\",\"name\":\"wine-2853916 - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2024-10-18T09:59:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wine-2853916-scaled-e1729245625815.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wine-2853916-scaled-e1729245625815.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/wine-2853916-scaled-e1729245625815.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"wine-2853916\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"wine-2853916 - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg","og_locale":"en_US","og_type":"article","og_title":"wine-2853916 - Localliving","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","og_image":[{"width":2560,"height":1707,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg","name":"wine-2853916 - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2024-10-18T09:59:53+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"wine-2853916"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-300x200.jpg 300w, https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-1024x683.jpg 1024w, https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-768x512.jpg 768w, https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-1536x1024.jpg 1536w, https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2020\/06\/wine-2853916-scaled.jpg","filesize":606391,"sizes":{"medium":{"file":"wine-2853916-300x200.jpg","width":300,"height":200,"filesize":12702,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-300x200.jpg"},"large":{"file":"wine-2853916-1024x683.jpg","width":1024,"height":683,"filesize":123036,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-1024x683.jpg"},"thumbnail":{"file":"wine-2853916-150x150.jpg","width":150,"height":150,"filesize":5197,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-150x150.jpg"},"medium_large":{"file":"wine-2853916-768x512.jpg","width":768,"height":512,"filesize":71850,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-768x512.jpg"},"1536x1536":{"file":"wine-2853916-1536x1024.jpg","width":1536,"height":1024,"filesize":253038,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-1536x1024.jpg"},"2048x2048":{"file":"wine-2853916-2048x1365.jpg","width":2048,"height":1365,"filesize":417518,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-2048x1365.jpg"},"homepage-banner-lg":{"file":"wine-2853916-1980x440.jpg","width":1980,"height":440,"filesize":158735,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-1980x440.jpg"},"homepage-banner-md":{"file":"wine-2853916-1170x440.jpg","width":1170,"height":440,"filesize":101424,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-1170x440.jpg"},"homepage-banner-sm":{"file":"wine-2853916-970x440.jpg","width":970,"height":440,"filesize":83543,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-970x440.jpg"},"homepage-banner-xs":{"file":"wine-2853916-750x440.jpg","width":750,"height":440,"filesize":63155,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-750x440.jpg"},"homepage-coupled-image":{"file":"wine-2853916-6000x224.jpg","width":6000,"height":224,"filesize":165641,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-6000x224.jpg"},"homepage-coupled-image-xs":{"file":"wine-2853916-750x224.jpg","width":750,"height":224,"filesize":38271,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-750x224.jpg"},"homepage-omrader":{"file":"wine-2853916-400x233.jpg","width":400,"height":233,"filesize":19821,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-400x233.jpg"},"homepage-underbanner-first":{"file":"wine-2853916-223x332.jpg","width":223,"height":332,"filesize":14025,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-223x332.jpg"},"homepage-underbanner-last":{"file":"wine-2853916-234x332.jpg","width":234,"height":332,"filesize":14996,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-234x332.jpg"},"homepage-underbanner-middle":{"file":"wine-2853916-239x162.jpg","width":239,"height":162,"filesize":8650,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-239x162.jpg"},"city-image":{"file":"wine-2853916-239x162.jpg","width":239,"height":162,"filesize":8650,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-239x162.jpg"},"static-page-featured-image":{"file":"wine-2853916-840x310.jpg","width":840,"height":310,"filesize":55665,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-840x310.jpg"},"category-results-stripe":{"file":"wine-2853916-6000x245.jpg","width":6000,"height":245,"filesize":181930,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-6000x245.jpg"},"full":{"file":"wine-2853916-scaled-e1729245625815.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"wine-2853916.jpg"},"post":null,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2020\/06\/wine-2853916-scaled-e1729245625815.jpg","filename":"wine-2853916.jpg","filesize":606391,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/7876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=7876"}]}}