{"id":6868,"date":"2023-02-27T12:53:07","date_gmt":"2023-02-27T12:53:07","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2.jpg"},"modified":"2023-03-16T09:47:32","modified_gmt":"2023-03-16T09:47:32","slug":"nils-schirmer-ru4reavlzf4-unsplash-3-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/nils-schirmer-ru4reavlzf4-unsplash-3-2\/","title":{"rendered":"nils-schirmer-RU4rEaVLZf4-unsplash"},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-6868","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>nils-schirmer-RU4rEaVLZf4-unsplash - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nils-schirmer-RU4rEaVLZf4-unsplash - Localliving\" \/>\n<meta property=\"og:description\" content=\"Ferie i Assisi Italien\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-16T09:47:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg\",\"name\":\"nils-schirmer-RU4rEaVLZf4-unsplash - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2023-02-27T12:53:07+00:00\",\"dateModified\":\"2023-03-16T09:47:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"nils-schirmer-RU4rEaVLZf4-unsplash\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"nils-schirmer-RU4rEaVLZf4-unsplash - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"nils-schirmer-RU4rEaVLZf4-unsplash - Localliving","og_description":"Ferie i Assisi Italien","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","article_modified_time":"2023-03-16T09:47:32+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","name":"nils-schirmer-RU4rEaVLZf4-unsplash - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2023-02-27T12:53:07+00:00","dateModified":"2023-03-16T09:47:32+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"nils-schirmer-RU4rEaVLZf4-unsplash"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"Ferie i Assisi Italien\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-300x200.jpg 300w, https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ferie i Assisi Italien<\/p>\n"},"caption":{"rendered":"<p>Ferie i Assisi Italien<\/p>\n"},"alt_text":"Ferie i Assisi Italien","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1706,"file":"2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","filesize":879423,"sizes":{"medium":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-300x200.jpg","width":300,"height":200,"filesize":14571,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-300x200.jpg"},"large":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-1024x683.jpg","width":1024,"height":683,"filesize":142257,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-1024x683.jpg"},"thumbnail":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-150x150.jpg","width":150,"height":150,"filesize":6731,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-150x150.jpg"},"homepage-banner-md":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-1170x440.jpg","width":1170,"height":440,"filesize":118884,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-1170x440.jpg"},"homepage-banner-sm":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-970x440.jpg","width":970,"height":440,"filesize":96530,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-970x440.jpg"},"homepage-underbanner-first":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-223x332.jpg","width":223,"height":332,"filesize":17530,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-223x332.jpg"},"city-image":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-239x162.jpg","width":239,"height":162,"filesize":10241,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-239x162.jpg"},"category-results-stripe":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-5866x245.jpg","width":5866,"height":245,"filesize":367132,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-5866x245.jpg"},"full":{"file":"nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","width":2560,"height":1706,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"nils-schirmer-RU4rEaVLZf4-unsplash-2.jpg"},"post":null,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/nils-schirmer-RU4rEaVLZf4-unsplash-2-scaled.jpg","filename":"nils-schirmer-RU4rEaVLZf4-unsplash-2.jpg","filesize":879423,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/6868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=6868"}]}}