{"id":6848,"date":"2023-02-27T11:36:16","date_gmt":"2023-02-27T11:36:16","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash.jpg"},"modified":"2023-03-16T09:51:34","modified_gmt":"2023-03-16T09:51:34","slug":"carmen-laezza-g6yn2nsxkhe-unsplash-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/carmen-laezza-g6yn2nsxkhe-unsplash-2\/","title":{"rendered":"carmen-laezza-G6yn2nsXkHE-unsplash"},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-6848","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>carmen-laezza-G6yn2nsXkHE-unsplash - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carmen-laezza-G6yn2nsXkHE-unsplash - Localliving\" \/>\n<meta property=\"og:description\" content=\"Kultur i Spoleto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-16T09:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2327\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg\",\"name\":\"carmen-laezza-G6yn2nsXkHE-unsplash - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2023-02-27T11:36:16+00:00\",\"dateModified\":\"2023-03-16T09:51:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"carmen-laezza-G6yn2nsXkHE-unsplash\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"carmen-laezza-G6yn2nsXkHE-unsplash - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"carmen-laezza-G6yn2nsXkHE-unsplash - Localliving","og_description":"Kultur i Spoleto","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","article_modified_time":"2023-03-16T09:51:34+00:00","og_image":[{"width":2327,"height":2560,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","name":"carmen-laezza-G6yn2nsXkHE-unsplash - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2023-02-27T11:36:16+00:00","dateModified":"2023-03-16T09:51:34+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"carmen-laezza-G6yn2nsXkHE-unsplash"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"273\" height=\"300\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-273x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Kultur i Spoleto\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-273x300.jpg 273w, https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-931x1024.jpg 931w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a><\/p>\n<p>Kultur i Spoleto<\/p>\n"},"caption":{"rendered":"<p>Kultur i Spoleto<\/p>\n"},"alt_text":"Kultur i Spoleto","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2327,"height":2560,"file":"2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","filesize":901819,"sizes":{"medium":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-273x300.jpg","width":273,"height":300,"filesize":16846,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-273x300.jpg"},"large":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-931x1024.jpg","width":931,"height":1024,"filesize":164926,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-931x1024.jpg"},"thumbnail":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-150x150.jpg","width":150,"height":150,"filesize":5794,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-150x150.jpg"},"homepage-banner-md":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-1170x440.jpg","width":1170,"height":440,"filesize":95458,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-1170x440.jpg"},"homepage-banner-sm":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-970x440.jpg","width":970,"height":440,"filesize":78499,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-970x440.jpg"},"homepage-underbanner-first":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-223x332.jpg","width":223,"height":332,"filesize":14983,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-223x332.jpg"},"city-image":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-239x162.jpg","width":239,"height":162,"filesize":9277,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-239x162.jpg"},"category-results-stripe":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-2344x245.jpg","width":2344,"height":245,"filesize":93516,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-2344x245.jpg"},"full":{"file":"carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","width":2327,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"carmen-laezza-G6yn2nsXkHE-unsplash.jpg"},"post":null,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/carmen-laezza-G6yn2nsXkHE-unsplash-scaled.jpg","filename":"carmen-laezza-G6yn2nsXkHE-unsplash.jpg","filesize":901819,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/6848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=6848"}]}}