{"id":6049,"date":"2023-02-17T11:25:45","date_gmt":"2023-02-17T11:25:45","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash.jpg"},"modified":"2023-02-17T11:25:45","modified_gmt":"2023-02-17T11:25:45","slug":"andrea-cevenini-xl9klu4tejs-unsplash-2-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/andrea-cevenini-xl9klu4tejs-unsplash-2-2\/","title":{"rendered":"andrea-cevenini-Xl9klU4tejs-unsplash"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-6049","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>andrea-cevenini-Xl9klU4tejs-unsplash - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"andrea-cevenini-Xl9klU4tejs-unsplash - Localliving\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg\",\"name\":\"andrea-cevenini-Xl9klU4tejs-unsplash - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2023-02-17T11:25:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"andrea-cevenini-Xl9klU4tejs-unsplash\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"andrea-cevenini-Xl9klU4tejs-unsplash - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","og_locale":"en_US","og_type":"article","og_title":"andrea-cevenini-Xl9klU4tejs-unsplash - Localliving","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","og_image":[{"width":2560,"height":1690,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","name":"andrea-cevenini-Xl9klU4tejs-unsplash - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2023-02-17T11:25:45+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"andrea-cevenini-Xl9klU4tejs-unsplash"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"198\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-300x198.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-300x198.jpg 300w, https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-1024x676.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1690,"file":"2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","filesize":773585,"sizes":{"medium":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-300x198.jpg","width":300,"height":198,"filesize":16668,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-300x198.jpg"},"large":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-1024x676.jpg","width":1024,"height":676,"filesize":151029,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-1024x676.jpg"},"thumbnail":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-150x150.jpg","width":150,"height":150,"filesize":7086,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-150x150.jpg"},"homepage-banner-md":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-1170x440.jpg","width":1170,"height":440,"filesize":100340,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-1170x440.jpg"},"homepage-banner-sm":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-970x440.jpg","width":970,"height":440,"filesize":89110,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-970x440.jpg"},"homepage-underbanner-first":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-223x332.jpg","width":223,"height":332,"filesize":17766,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-223x332.jpg"},"city-image":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-239x162.jpg","width":239,"height":162,"filesize":11625,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-239x162.jpg"},"category-results-stripe":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-5991x245.jpg","width":5991,"height":245,"filesize":154507,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-5991x245.jpg"},"full":{"file":"andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","width":2560,"height":1690,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"andrea-cevenini-Xl9klU4tejs-unsplash.jpg"},"post":null,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2023\/02\/andrea-cevenini-Xl9klU4tejs-unsplash-scaled.jpg","filename":"andrea-cevenini-Xl9klU4tejs-unsplash.jpg","filesize":773585,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/6049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=6049"}]}}