{"id":3733,"date":"2015-02-24T08:30:24","date_gmt":"2015-02-24T08:30:24","guid":{"rendered":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg"},"modified":"2020-12-07T14:38:04","modified_gmt":"2020-12-07T14:38:04","slug":"walk-on-tuscan-chianti-hills-3-2","status":"inherit","type":"attachment","link":"https:\/\/localliving.dk\/en\/wine\/walk-on-tuscan-chianti-hills-3-2\/","title":{"rendered":"Smag Italienske vine p\u00e5 din ferie til Italien"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"class_list":["post-3733","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Smag Italienske vine p\u00e5 din ferie til Italien - Localliving<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smag Italienske vine p\u00e5 din ferie til Italien - Localliving\" \/>\n<meta property=\"og:description\" content=\"Hold din n\u00e6ste ferie i en af Local Livings ferieboliger i Italien s\u00e5 er dette sted muligt at bes\u00f8ge!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Localliving\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LocalLivingDK\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-07T14:38:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/walk-on-tuscan-Chianti-hills2.jpg\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/walk-on-tuscan-Chianti-hills2.jpg\",\"name\":\"Smag Italienske vine p\u00e5 din ferie til Italien - Localliving\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\"},\"datePublished\":\"2015-02-24T08:30:24+00:00\",\"dateModified\":\"2020-12-07T14:38:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/walk-on-tuscan-Chianti-hills2.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/walk-on-tuscan-Chianti-hills2.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/walk-on-tuscan-Chianti-hills2.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wine\",\"item\":\"https:\\\/\\\/localliving.dk\\\/en\\\/wine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Smag Italienske vine p\u00e5 din ferie til Italien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#website\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"name\":\"Localliving\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/localliving.dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#organization\",\"name\":\"Localliving\",\"url\":\"https:\\\/\\\/localliving.dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"contentUrl\":\"https:\\\/\\\/localliving.dk\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-video-Semitransperant-baggrund.png\",\"width\":2500,\"height\":459,\"caption\":\"Localliving\"},\"image\":{\"@id\":\"https:\\\/\\\/localliving.dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LocalLivingDK\",\"https:\\\/\\\/www.instagram.com\\\/locallivingdk\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/company\\\/local-living-a-s\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9GA6ad3XYyzSI-tkLJ0zpg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Smag Italienske vine p\u00e5 din ferie til Italien - Localliving","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","og_locale":"en_US","og_type":"article","og_title":"Smag Italienske vine p\u00e5 din ferie til Italien - Localliving","og_description":"Hold din n\u00e6ste ferie i en af Local Livings ferieboliger i Italien s\u00e5 er dette sted muligt at bes\u00f8ge!","og_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","og_site_name":"Localliving","article_publisher":"https:\/\/www.facebook.com\/LocalLivingDK","article_modified_time":"2020-12-07T14:38:04+00:00","og_image":[{"width":840,"height":310,"url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","name":"Smag Italienske vine p\u00e5 din ferie til Italien - Localliving","isPartOf":{"@id":"https:\/\/localliving.dk\/#website"},"datePublished":"2015-02-24T08:30:24+00:00","dateModified":"2020-12-07T14:38:04+00:00","breadcrumb":{"@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/localliving.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Wine","item":"https:\/\/localliving.dk\/en\/wine\/"},{"@type":"ListItem","position":3,"name":"Smag Italienske vine p\u00e5 din ferie til Italien"}]},{"@type":"WebSite","@id":"https:\/\/localliving.dk\/#website","url":"https:\/\/localliving.dk\/","name":"Localliving","description":"","publisher":{"@id":"https:\/\/localliving.dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/localliving.dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/localliving.dk\/#organization","name":"Localliving","url":"https:\/\/localliving.dk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/","url":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","contentUrl":"https:\/\/localliving.dk\/wp-content\/uploads\/2025\/02\/logo-video-Semitransperant-baggrund.png","width":2500,"height":459,"caption":"Localliving"},"image":{"@id":"https:\/\/localliving.dk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LocalLivingDK","https:\/\/www.instagram.com\/locallivingdk\/","https:\/\/dk.linkedin.com\/company\/local-living-a-s","https:\/\/www.youtube.com\/channel\/UC9GA6ad3XYyzSI-tkLJ0zpg"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-300x111.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-300x111.jpg 300w, https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg 840w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Hold din n\u00e6ste ferie i en af Local Livings ferieboliger i Italien s\u00e5 er dette sted muligt at bes\u00f8ge!<\/p>\n"},"caption":{"rendered":"<p>Hold din n\u00e6ste ferie i en af Local Livings ferieboliger i Italien s\u00e5 er dette sted muligt at bes\u00f8ge!<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":840,"height":310,"file":"2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","sizes":{"thumbnail":{"file":"walk-on-tuscan-Chianti-hills2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-150x150.jpg"},"medium":{"file":"walk-on-tuscan-Chianti-hills2-300x111.jpg","width":300,"height":111,"width_query":"300","height_query":"300","mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-300x111.jpg"},"homepage-banner-xs":{"file":"walk-on-tuscan-Chianti-hills2-750x310.jpg","width":750,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-750x310.jpg"},"homepage-coupled-image":{"file":"walk-on-tuscan-Chianti-hills2-840x224.jpg","width":840,"height":224,"width_query":9999,"height_query":224,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-840x224.jpg"},"homepage-omrader":{"file":"walk-on-tuscan-Chianti-hills2-258x150.jpg","width":258,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-258x150.jpg"},"homepage-underbanner-first":{"file":"walk-on-tuscan-Chianti-hills2-223x310.jpg","width":223,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-223x310.jpg"},"homepage-underbanner-last":{"file":"walk-on-tuscan-Chianti-hills2-234x310.jpg","width":234,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-234x310.jpg"},"homepage-underbanner-middle":{"file":"walk-on-tuscan-Chianti-hills2-239x162.jpg","width":239,"height":162,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-239x162.jpg"},"city-image":{"file":"walk-on-tuscan-Chianti-hills2-239x162.jpg","width":239,"height":162,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-239x162.jpg"},"static-page-featured-image":{"file":"walk-on-tuscan-Chianti-hills2-840x310.jpg","width":840,"height":310,"width_query":840,"height_query":310,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-840x310.jpg"},"600x99999":{"file":"walk-on-tuscan-Chianti-hills2-600x310.jpg","width":600,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2-600x310.jpg"},"full":{"file":"walk-on-tuscan-Chianti-hills2.jpg","width":840,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":571,"source_url":"https:\/\/localliving.dk\/wp-content\/uploads\/2015\/02\/walk-on-tuscan-Chianti-hills2.jpg","filename":"walk-on-tuscan-Chianti-hills2.jpg","filesize":165622,"_links":{"self":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media\/3733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/comments?post=3733"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":571,"href":"https:\/\/localliving.dk\/en\/wp-json\/wp\/v2\/pages\/571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}